{"id":8437,"date":"2022-12-05T13:23:31","date_gmt":"2022-12-05T12:23:31","guid":{"rendered":"https:\/\/educamos.com\/policita-de-privacidad\/"},"modified":"2025-12-01T14:47:32","modified_gmt":"2025-12-01T13:47:32","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8437\" class=\"elementor elementor-8437 elementor-5656\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d525731 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d525731\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-221af76\" data-id=\"221af76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e23413 elementor-widget elementor-widget-bloque-cabecera-menu\" data-id=\"6e23413\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bloque-cabecera-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <!-- Encabezado -->\n        <header class=\"header \">\n            <div id=\"sticky_header\" class=\"sticky-header \">\n                <div class=\"container\">\n                    <div class=\"row\">\n                        <div class=\"col-12 d-flex justify-content-between align-items-center\">\n                            <div class=\"logo\"><a href=\"https:\/\/educamos.com\/es-mx\/\"><img decoding=\"async\" src=\"https:\/\/educamos.com\/wp-content\/themes\/educamos\/images\/logotipo-2026.png\" class=\"img-fluid\" alt=\"Logotipo de Educamos\" \/><\/a><\/div>\n                                                            <div class=\"menu-header\">\n                                                                        <a href=\"\/es-mx\/solicita-una-demo\" class=\"btn btn-primary demo\" title=\"Solicitar informaci\u00f3n\"><span class=\"d-none d-sm-block\">Solicitar informaci\u00f3n<\/span><span class=\"d-block d-sm-none\">M\u00e1s info<\/span><\/a>\n                                                                        <button data-target=\"#main_menu\" data-toggle=\"collapse\" class=\"navbar-toggle openMenu\" type=\"button\">\n                                        <i class=\"far fa-bars\"><\/i> <span class=\"sr-only\">Abrir men\u00fa<\/span>\n                                        <i class=\"far fa-times\"><\/i> <span class=\"sr-only\">Cerrar men\u00fa<\/span>    \n                                    <\/button>\n                                <\/div>\n\n                                <!-- MEGAMENU -->\n                                <div class=\"megamenu\">\n                                    <div class=\"container\">\n                                    <ul id=\"menu-menu-principal-mexico\" class=\"dropdown-menu\" itemscope itemtype=\"http:\/\/www.schema.org\/SiteNavigationElement\"><li  id=\"menu-item-8943\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children dropdown menu-item-8943 nav-item\"><a href=\"#\" aria-expanded=\"false\" class=\"dropdown-toggle nav-link\" id=\"menu-item-dropdown-8943\" data-bs-toggle=\"dropdown\"><span itemprop=\"name\">Educamos<\/span><\/a>\n<ul class=\"dropdown-menu\" aria-labelledby=\"menu-item-dropdown-8943\">\n\t<li  id=\"menu-item-10147\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-10147 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/que-es\/\" class=\"dropdown-item\"><span itemprop=\"name\">\u00bfQu\u00e9 es?<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10146\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-10146 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/por-que\/\" class=\"dropdown-item\"><span itemprop=\"name\">\u00bfPor qu\u00e9?<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10149\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-10149 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/educamos-makers\/\" class=\"dropdown-item\"><span itemprop=\"name\">Educamos Makers<\/span><\/a><\/li>\n\t<li  id=\"menu-item-13018\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-13018 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/contacto\/\" class=\"dropdown-item\"><span itemprop=\"name\">Contacto<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<li  id=\"menu-item-8944\" class=\"menu-item menu-item-type-post_type_archive menu-item-object-funcionalidades menu-item-has-children dropdown menu-item-8944 nav-item\"><a href=\"#\" aria-expanded=\"false\" class=\"dropdown-toggle nav-link\" id=\"menu-item-dropdown-8944\" data-bs-toggle=\"dropdown\"><span itemprop=\"name\">Funcionalidades<\/span><\/a>\n<ul class=\"dropdown-menu\" aria-labelledby=\"menu-item-dropdown-8944\">\n\t<li  id=\"menu-item-10152\" class=\"menu-item menu-item-type-post_type menu-item-object-funcionalidades menu-item-10152 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/funcionalidades\/analitica-de-datos\/\" class=\"dropdown-item\"><span itemprop=\"name\">Anal\u00edtica de datos<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10153\" class=\"menu-item menu-item-type-post_type menu-item-object-funcionalidades menu-item-10153 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/funcionalidades\/comunicacion-del-centro\/\" class=\"dropdown-item\"><span itemprop=\"name\">Comunicaci\u00f3n del centro<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10151\" class=\"menu-item menu-item-type-post_type menu-item-object-funcionalidades menu-item-10151 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/funcionalidades\/gestion-del-centro\/\" class=\"dropdown-item\"><span itemprop=\"name\">Gesti\u00f3n del centro<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10150\" class=\"menu-item menu-item-type-post_type menu-item-object-funcionalidades menu-item-10150 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/funcionalidades\/innovacion-pedagogica\/\" class=\"dropdown-item\"><span itemprop=\"name\">Innovaci\u00f3n pedag\u00f3gica<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<li  id=\"menu-item-8945\" class=\"menu-item menu-item-type-post_type_archive menu-item-object-beneficios menu-item-has-children dropdown menu-item-8945 nav-item\"><a href=\"#\" aria-expanded=\"false\" class=\"dropdown-toggle nav-link\" id=\"menu-item-dropdown-8945\" data-bs-toggle=\"dropdown\"><span itemprop=\"name\">Beneficios para<\/span><\/a>\n<ul class=\"dropdown-menu\" aria-labelledby=\"menu-item-dropdown-8945\">\n\t<li  id=\"menu-item-10157\" class=\"menu-item menu-item-type-post_type menu-item-object-beneficios menu-item-10157 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/beneficios\/centros-educativos\/\" class=\"dropdown-item\"><span itemprop=\"name\">Centros educativos<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10158\" class=\"menu-item menu-item-type-post_type menu-item-object-beneficios menu-item-10158 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/beneficios\/red-de-escuelas\/\" class=\"dropdown-item\"><span itemprop=\"name\">Red de escuelas<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10155\" class=\"menu-item menu-item-type-post_type menu-item-object-beneficios menu-item-10155 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/beneficios\/docentes\/\" class=\"dropdown-item\"><span itemprop=\"name\">Docentes<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10156\" class=\"menu-item menu-item-type-post_type menu-item-object-beneficios menu-item-10156 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/beneficios\/familias\/\" class=\"dropdown-item\"><span itemprop=\"name\">Familias<\/span><\/a><\/li>\n\t<li  id=\"menu-item-10154\" class=\"menu-item menu-item-type-post_type menu-item-object-beneficios menu-item-10154 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/beneficios\/alumnos-as\/\" class=\"dropdown-item\"><span itemprop=\"name\">Alumnos\/as<\/span><\/a><\/li>\n\t<li  id=\"menu-item-16224\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-16224 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/beneficios\/formacion-profesional\/\" class=\"dropdown-item\"><span itemprop=\"name\">Formaci\u00f3n Profesional<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<li  id=\"menu-item-8961\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children dropdown menu-item-8961 nav-item\"><a href=\"#\" aria-expanded=\"false\" class=\"dropdown-toggle nav-link\" id=\"menu-item-dropdown-8961\" data-bs-toggle=\"dropdown\"><span itemprop=\"name\">Insights<\/span><\/a>\n<ul class=\"dropdown-menu\" aria-labelledby=\"menu-item-dropdown-8961\">\n\t<li  id=\"menu-item-20608\" class=\"menu-item menu-item-type-taxonomy menu-item-object-category menu-item-20608 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/blog\/\" class=\"dropdown-item\"><span itemprop=\"name\">Blog<\/span><\/a><\/li>\n\t<li  id=\"menu-item-20609\" class=\"menu-item menu-item-type-post_type_archive menu-item-object-ebook menu-item-20609 nav-item\"><a itemprop=\"url\" href=\"https:\/\/educamos.com\/es-mx\/ebook\/\" class=\"dropdown-item\"><span itemprop=\"name\">Ebooks<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<li  id=\"menu-item-8963\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children dropdown menu-item-8963 nav-item\"><a href=\"#\" aria-expanded=\"false\" class=\"dropdown-toggle nav-link\" id=\"menu-item-dropdown-8963\" data-bs-toggle=\"dropdown\"><span itemprop=\"name\">Clientes<\/span><\/a>\n<ul class=\"dropdown-menu\" aria-labelledby=\"menu-item-dropdown-8963\">\n\t<li  id=\"menu-item-8964\" class=\"link-externo menu-item menu-item-type-custom menu-item-object-custom menu-item-8964 nav-item\"><a target=\"_blank\" rel=\"noopener noreferrer\" itemprop=\"url\" href=\"https:\/\/www.educamosmakers.com\/\" class=\"dropdown-item\"><span itemprop=\"name\">Comunidad Educamos Makers<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/header>\n        <!-- \/ -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ac9ea5 elementor-widget elementor-widget-bloque-texto\" data-id=\"3ac9ea5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bloque-texto.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <!-- Texto a 2 columnas-->\n        <section class=\"bloque bloque-texto \">\n            <div class=\"container\">\n                <h1 class=\"titulos\" data-aos=\"fade-left\" data-aos-duration=\"700\">Pol\u00edtica de privacidad<\/h1>                <div class=\"estrecho2\">\n                    <div class=\"row\">\n                        <div class=\"col-sm-12\">\n                            <div class=\"the_content\" data-aos=\"fade-up\" data-aos-duration=\"700\">\n                                <p>Este sitio web (en adelante, la Web) es propiedad de <strong>TECNOLOG\u00cdA Y GESTI\u00d3N EDUCATIVA, S.L.U.<\/strong> (en adelante, TGE), con domicilio social en calle Impresores, n\u00ba 2 (Parque Empresarial Prado del Espino), 28660 Boadilla del Monte, Madrid, Espa\u00f1a y C.I.F. n\u00ba B-86267432, inscrita en el Registro Mercantil de Madrid al Tomo 20087, Folio 160, Hoja M-523700.<\/p><p>Servicio de atenci\u00f3n al cliente y Delegado de protecci\u00f3n de datos: <a href=\"https:\/\/contactodpo.educamos.com\" target=\"_blank\" rel=\"noopener\">https:\/\/contactodpo.educamos.com<\/a><\/p><p>Es compromiso de TGE respetar la privacidad y asegurar la protecci\u00f3n de los datos personales de quienes acceden y\/o son usuarios de la Web. Por ello, por medio de este documento, le informamos sobre la forma en la que recogemos, tratamos y protegemos su informaci\u00f3n personal, tanto aquella que nos facilita directamente, como la derivada de la navegaci\u00f3n, uso y disfrute de los contenidos y servicios asociados a la Web.<\/p><p>El usuario debe leer con atenci\u00f3n esta Pol\u00edtica de privacidad y determinar, libre y voluntariamente, si desea facilitar sus datos personales a TGE en las condiciones que se establecen en la misma.<\/p><h2>1. \u00bfCON QU\u00c9 FINALIDAD TRATAREMOS SUS DATOS PERSONALES Y DURANTE CU\u00c1NTO TIEMPO?<\/h2><p>Sus datos personales ser\u00e1n tratados por TGE conforme a las siguientes finalidades:<\/p><ul><li>Gestionar los servicios y ventajas que ofrece a los usuarios de la Web.<\/li><li>Atender las solicitudes de contacto e informaci\u00f3n.<\/li><li>Gestionar el env\u00edo por cualquier medio, incluidos los electr\u00f3nicos, comunicaciones y ofertas comerciales de productos y servicios propios, fundamentalmente en los \u00e1mbitos editorial, de formaci\u00f3n y educaci\u00f3n.<\/li><li>Los datos tambi\u00e9n se podr\u00e1n utilizar para la elaboraci\u00f3n de un perfil comercial del afectado que permita un mejor cumplimiento de las finalidades antedichas (prestaci\u00f3n del servicio, env\u00edo de comunicaciones ajustada a sus intereses, etc.). En ning\u00fan caso se adoptar\u00e1n decisiones automatizadas basadas en esta informaci\u00f3n.<\/li><\/ul><p>Los datos se conservar\u00e1n durante el tiempo necesario para la realizaci\u00f3n de las finalidades para las que fueron recogidos, salvo que el usuario solicite su baja a TGE, se oponga o revoque su consentimiento, o exista una obligaci\u00f3n legal de conservarlos por un tiempo superior.<\/p><h2>2. \u00bfQU\u00c9 DATOS TRATAREMOS?<\/h2><p>Las categor\u00edas de datos que ser\u00e1n objeto de tratamiento por parte de TGE vendr\u00e1n determinadas, en cada caso, por los formularios que figuran en las distintas secciones de la Web.<\/p><p>Adem\u00e1s de lo anterior, se podr\u00e1 realizar el tratamiento de la informaci\u00f3n derivada de la navegaci\u00f3n, uso y disfrute de los contenidos y servicios asociados a la Web por parte de sus usuarios, incluida la direcci\u00f3n IP.<\/p><p>En caso de que el usuario facilite datos de terceros, manifiesta estar legalmente legitimado para hacerlo y\/o, en su caso, contar con el consentimiento de los mismos, comprometi\u00e9ndose a trasladar al interesado, titular de dichos datos, la informaci\u00f3n contenida en esta Pol\u00edtica de privacidad, eximiendo a TGE de cualquier responsabilidad en este sentido. No obstante, TGE podr\u00e1 llevar a cabo las verificaciones necesarias para constatar este hecho, adoptando las medidas de diligencia debida que correspondan, conforme a la normativa de protecci\u00f3n de datos.<\/p><h2>3. \u00bfCU\u00c1NDO ES OBLIGATORIO FACILITAR DATOS?<\/h2><p>En la Web se indicar\u00e1 cu\u00e1les de los datos solicitados tienen car\u00e1cter obligatorio para cumplir con las finalidades establecidas. Por lo tanto, si no se facilitan estos datos o no se facilitan correctamente, no podr\u00e1n atenderse las solicitudes de los usuarios o hacer uso del servicio o prestaci\u00f3n de que se trate.<\/p><h2>4. \u00bfCU\u00c1L ES LA LEGITIMACI\u00d3N DEL TRATAMIENTO DE SUS DATOS?<\/h2><p>El tratamiento de datos para la gesti\u00f3n de los servicios de la Web es necesario para la eficaz ejecuci\u00f3n de la relaci\u00f3n contractual con los usuarios. El tratamiento de datos para la atenci\u00f3n de las solicitudes de contacto e informaci\u00f3n estar\u00e1 basado en el propio consentimiento del usuario, manifestado al realizar la correspondiente consulta o solicitud.<\/p><p>Por su parte, la base legal para el uso de los datos con fines de marketing, incluido la realizaci\u00f3n de un perfil comercial para asegurar que las comunicaciones se ajustan a los intereses del afectado, ser\u00e1 (1) si este tiene la consideraci\u00f3n de cliente, el inter\u00e9s leg\u00edtimo de TGE reconocido por la normativa, al limitarse este uso a productos y servicios exclusivamente de TGE y del mismo tipo que los de la Web (siempre en los \u00e1mbitos editorial, de formaci\u00f3n y educaci\u00f3n); y (2) en los dem\u00e1s supuestos (por ejemplo, solicitudes de contacto e informaci\u00f3n), el consentimiento. El uso de la Web no estar\u00e1 supeditado a la aceptaci\u00f3n de este tratamiento con finalidades de marketing, por lo que estar\u00e1n habilitados los correspondientes procedimientos para oponerse al tratamiento o prestar el consentimiento oportuno, seg\u00fan el caso.<\/p><h2>5. \u00bfPUEDO RECIBIR COMUNICACIONES COMERCIALES Y PROMOCIONALES?<\/h2><p>Siempre que se realice alguna comunicaci\u00f3n de este tipo, la misma se ajustar\u00e1 a las finalidades indicadas en esta Pol\u00edtica y ser\u00e1 dirigida \u00fanica y exclusivamente a aquellos usuarios respecto de los que TGE tenga la legitimaci\u00f3n correspondiente, seg\u00fan lo se\u00f1alado m\u00e1s arriba.<\/p><p>Adem\u00e1s, en caso de que en un futuro desee oponerse al tratamiento o revocar su consentimiento y dejar de recibir comunicaciones comerciales o promocionales, puede solicitarlo dirigi\u00e9ndose a nuestro Delegado de protecci\u00f3n de datos, o indic\u00e1ndolo mediante la opci\u00f3n de baja proporcionada en cada una de las comunicaciones comerciales enviadas. La realizaci\u00f3n de estas acciones no afectar\u00e1 a la licitud de los tratamientos efectuados con anterioridad.<\/p><h2>6. \u00bfCON QUI\u00c9N COMPARTIREMOS LOS DATOS?<\/h2><p>Los datos del usuario podr\u00e1n ser comunicados a:<\/p><ul><li>Administraciones P\u00fablicas, en los casos previstos por la Ley.<\/li><li>Cuando las condiciones legales de las acciones que se realicen a trav\u00e9s de la Web (por ejemplo, concursos, promociones, etc.) as\u00ed lo indiquen expresamente, determinados datos podr\u00e1n ser publicados por TGE en la Web o cualquier otro portal o redes sociales (Twitter, Facebook, Instagram, etc.) de TGE.<\/li><li>A los comercializadores autorizados de TGE en el territorio del usuario, ya sea porque (i) lo necesiten para la gesti\u00f3n de los servicios de la Web o para la resoluci\u00f3n de la solicitud de informaci\u00f3n recibida, o bien (ii) siempre que estemos legitimados para ello, seg\u00fan lo indicado m\u00e1s arriba, para el env\u00edo de comunicaciones comerciales sobre los productos y servicios ofertados por TGE, en los \u00e1mbitos editorial, de formaci\u00f3n y educaci\u00f3n.<\/li><\/ul><p>Adicionalmente, los datos podr\u00e1n ser accesibles por proveedores de TGE, siempre que sea necesario u oportuno para el adecuado cumplimiento de las obligaciones legales y\/o de las finalidades anteriormente indicadas. Dichos proveedores no tratar\u00e1n sus datos para finalidades propias.<\/p><h2>7. \u00bfD\u00d3NDE SE VAN A TRATAR LOS DATOS?<\/h2><p>En caso de que para el correcto desarrollo de la relaci\u00f3n de los usuarios con TGE resulte absolutamente necesario que el tratamiento de los datos personales se realice, parcial o totalmente, fuera del territorio nacional (en el caso de usuarios de Espa\u00f1a, fuera del Espacio Econ\u00f3mico Europeo), quedar\u00e1 garantizando un nivel adecuado de protecci\u00f3n de acuerdo con la legislaci\u00f3n aplicable, ya sea porque el pa\u00eds u organizaci\u00f3n de destino ofrezca dicha garant\u00eda, o porque la persona o entidad encargada del tratamiento se haya comprometido contractualmente a la misma. Si desea m\u00e1s informaci\u00f3n sobre estas garant\u00edas, contacte el Delegado de Protecci\u00f3n de Datos de TGE.<\/p><h2>8. \u00bfQU\u00c9 DERECHOS TIENE EL USUARIO, Y C\u00d3MO PUEDE EJERCITARLOS?<\/h2><p>En cualquier momento y de manera gratuita, el usuario puede ejercitar los derechos reconocidos por la normativa de protecci\u00f3n de datos ante TGE (revocar consentimientos, acceder a los datos que est\u00e1n siendo tratados, rectificarlos, solicitar su supresi\u00f3n o portabilidad y\/o limitar su tratamiento, seg\u00fan sea exigible).<\/p><p>Para el ejercicio de los derechos ser\u00e1 preciso ponerse en contacto con el Delegado de protecci\u00f3n de datos de TGE por los canales m\u00e1s arriba indicados, se\u00f1alando el derecho o derechos que desee ejercitar. TGE estudiar\u00e1 su solicitud con la finalidad de darle una respuesta a la mayor brevedad posible. Por favor, tenga en cuenta que los derechos se\u00f1alados solo podr\u00e1n ser atendidos en los supuestos previstos por la normativa de protecci\u00f3n de datos.<\/p><p>Igualmente, si lo estima oportuno, puede presentar una reclamaci\u00f3n ante la autoridad competente en la materia.<\/p><h2>9. \u00bfQU\u00c9 RESPONSABILIDADES TIENE EL USUARIO EN RELACI\u00d3N CON LOS DATOS?<\/h2><p>El usuario:<\/p><ul><li>Garantiza que tiene la edad legal y capacidad jur\u00eddica necesaria para facilitar a TGE y autorizar el tratamiento de los datos en los t\u00e9rminos de la presente Pol\u00edtica de Privacidad, y que dichos datos son verdaderos, exactos, completos y actualizados. A estos efectos, el usuario responde de la veracidad de todos los datos que comunique y mantendr\u00e1 convenientemente actualizada la informaci\u00f3n facilitada, de tal forma que responda a su situaci\u00f3n real.<\/li><li>Garantiza que, en caso de facilitar datos de terceros, ha informado a los mismos de todos los aspectos contenidos en esta Pol\u00edtica de Privacidad as\u00ed como que, o bien est\u00e1 legalmente legitimado para realizar dicha comunicaci\u00f3n de datos para los fines se\u00f1alados o, en su caso, que ha obtenido la autorizaci\u00f3n del tercero para ello.<\/li><\/ul><p>Ser\u00e1 responsable de las informaciones falsas o inexactas que proporcione a trav\u00e9s de la Web y de los da\u00f1os y perjuicios, directos o indirectos, que ello cause a TGE o a terceros.<\/p><h2>10. \u00bfQU\u00c9 MEDIDAS DE SEGURIDAD ADOPTAREMOS EN EL TRATAMIENTO DE DATOS?.<\/h2><p>Los datos ser\u00e1n custodiados por TGE en sistemas que garanticen la m\u00e1xima confidencialidad y seguridad de la informaci\u00f3n, conforme a lo previsto en la normativa aplicable, adoptando al efecto las medidas de \u00edndole t\u00e9cnica y organizativas necesarias para evitar su alteraci\u00f3n, p\u00e9rdida, tratamiento o acceso no autorizado, habida cuenta del estado de la tecnolog\u00eda, la naturaleza de los datos y los riesgos a que est\u00e1n expuestos.<\/p><p><em>\u00daltima actualizaci\u00f3n: 01\/12\/2025<\/em><\/p>                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Solicitar informaci\u00f3nM\u00e1s info Abrir men\u00fa Cerrar men\u00fa Educamos \u00bfQu\u00e9 es? \u00bfPor qu\u00e9? Educamos Makers Contacto Funcionalidades Anal\u00edtica de datos Comunicaci\u00f3n del centro Gesti\u00f3n del centro Innovaci\u00f3n pedag\u00f3gica Beneficios para Centros educativos Red de escuelas Formaci\u00f3n Profesional Docentes Familias Alumnos\/as Insights Blog Ebooks Clientes Comunidad Educamos Cerca Pol\u00edtica de privacidad Este sitio web (en adelante, la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9400,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8437","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de privacidad | Educamos<\/title>\n<meta name=\"description\" content=\"Pol\u00edtica de privacidad: Este sitio web es propiedad de SM, con domicilio social en calle Impresores, n\u00ba 2 (Parque Empresarial Prado del Espino), 28660 Boadilla del Monte, Madrid, Espa\u00f1a y C.I.F. n\u00ba B-86267432, inscrita en el Registro Mercantil de Madrid al Tomo 20087, Folio 160, Hoja M-523700.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad | Educamos\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de privacidad: Este sitio web es propiedad de SM, con domicilio social en calle Impresores, n\u00ba 2 (Parque Empresarial Prado del Espino), 28660 Boadilla del Monte, Madrid, Espa\u00f1a y C.I.F. n\u00ba B-86267432, inscrita en el Registro Mercantil de Madrid al Tomo 20087, Folio 160, Hoja M-523700.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Educamos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T13:47:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/educamos.com\/wp-content\/uploads\/2023\/01\/rrss_generica_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/\",\"url\":\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/\",\"name\":\"Pol\u00edtica de privacidad | Educamos\",\"isPartOf\":{\"@id\":\"https:\/\/educamos.com\/es-mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/educamos.com\/wp-content\/uploads\/2023\/01\/rrss_generica_01.png\",\"datePublished\":\"2022-12-05T12:23:31+00:00\",\"dateModified\":\"2025-12-01T13:47:32+00:00\",\"description\":\"Pol\u00edtica de privacidad: Este sitio web es propiedad de SM, con domicilio social en calle Impresores, n\u00ba 2 (Parque Empresarial Prado del Espino), 28660 Boadilla del Monte, Madrid, Espa\u00f1a y C.I.F. n\u00ba B-86267432, inscrita en el Registro Mercantil de Madrid al Tomo 20087, Folio 160, Hoja M-523700.\",\"breadcrumb\":{\"@id\":\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#primaryimage\",\"url\":\"https:\/\/educamos.com\/wp-content\/uploads\/2023\/01\/rrss_generica_01.png\",\"contentUrl\":\"https:\/\/educamos.com\/wp-content\/uploads\/2023\/01\/rrss_generica_01.png\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/educamos.com\/es-mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/educamos.com\/es-mx\/#website\",\"url\":\"https:\/\/educamos.com\/es-mx\/\",\"name\":\"Educamos\",\"description\":\"La escuela de hoy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/educamos.com\/es-mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad | Educamos","description":"Pol\u00edtica de privacidad: Este sitio web es propiedad de SM, con domicilio social en calle Impresores, n\u00ba 2 (Parque Empresarial Prado del Espino), 28660 Boadilla del Monte, Madrid, Espa\u00f1a y C.I.F. n\u00ba B-86267432, inscrita en el Registro Mercantil de Madrid al Tomo 20087, Folio 160, Hoja M-523700.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/","og_locale":"es_MX","og_type":"article","og_title":"Pol\u00edtica de privacidad | Educamos","og_description":"Pol\u00edtica de privacidad: Este sitio web es propiedad de SM, con domicilio social en calle Impresores, n\u00ba 2 (Parque Empresarial Prado del Espino), 28660 Boadilla del Monte, Madrid, Espa\u00f1a y C.I.F. n\u00ba B-86267432, inscrita en el Registro Mercantil de Madrid al Tomo 20087, Folio 160, Hoja M-523700.","og_url":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/","og_site_name":"Educamos","article_modified_time":"2025-12-01T13:47:32+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/educamos.com\/wp-content\/uploads\/2023\/01\/rrss_generica_01.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/","url":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/","name":"Pol\u00edtica de privacidad | Educamos","isPartOf":{"@id":"https:\/\/educamos.com\/es-mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#primaryimage"},"image":{"@id":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/educamos.com\/wp-content\/uploads\/2023\/01\/rrss_generica_01.png","datePublished":"2022-12-05T12:23:31+00:00","dateModified":"2025-12-01T13:47:32+00:00","description":"Pol\u00edtica de privacidad: Este sitio web es propiedad de SM, con domicilio social en calle Impresores, n\u00ba 2 (Parque Empresarial Prado del Espino), 28660 Boadilla del Monte, Madrid, Espa\u00f1a y C.I.F. n\u00ba B-86267432, inscrita en el Registro Mercantil de Madrid al Tomo 20087, Folio 160, Hoja M-523700.","breadcrumb":{"@id":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#primaryimage","url":"https:\/\/educamos.com\/wp-content\/uploads\/2023\/01\/rrss_generica_01.png","contentUrl":"https:\/\/educamos.com\/wp-content\/uploads\/2023\/01\/rrss_generica_01.png","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/educamos.com\/es-mx\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/educamos.com\/es-mx\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/educamos.com\/es-mx\/#website","url":"https:\/\/educamos.com\/es-mx\/","name":"Educamos","description":"La escuela de hoy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/educamos.com\/es-mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/pages\/8437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/comments?post=8437"}],"version-history":[{"count":21,"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/pages\/8437\/revisions"}],"predecessor-version":[{"id":26691,"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/pages\/8437\/revisions\/26691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/media\/9400"}],"wp:attachment":[{"href":"https:\/\/educamos.com\/es-mx\/wp-json\/wp\/v2\/media?parent=8437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}